{"id":292,"date":"2023-06-06T07:24:33","date_gmt":"2023-06-06T07:24:33","guid":{"rendered":"https:\/\/gomeracorazonverde.com\/?page_id=292"},"modified":"2025-09-19T16:14:33","modified_gmt":"2025-09-19T16:14:33","slug":"semana-empoderamiento","status":"publish","type":"page","link":"https:\/\/gomeracorazonverde.com\/de\/semana-empoderamiento\/","title":{"rendered":"EMPOWERMENT-WOCHE"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.21.0&#8243; animation_direction=\u00bbtop\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbEncuentra tu fuerza en la naturaleza\u00bb content_max_width=\u00bb604px\u00bb _builder_version=\u00bb4.21.0&#8243; title_font=\u00bbLato||||||||\u00bb title_font_size=\u00bb60px\u00bb title_line_height=\u00bb1.2em\u00bb content_font=\u00bb||||||||\u00bb content_font_size=\u00bb20px\u00bb content_line_height=\u00bb1.8em\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb90deg\u00bb background_color_gradient_stops=\u00bbrgba(0,0,0,0.75) 0%|rgba(0,0,0,0) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,0,0,0.75)\u00bb background_color_gradient_end=\u00bbrgba(0,0,0,0)\u00bb background_image=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/vallehermoso_winter2020_WEB-6.jpg\u00bb custom_button_one=\u00bbon\u00bb button_one_text_size=\u00bb18px\u00bb button_one_bg_color=\u00bb#02d002&#8243; button_one_border_width=\u00bb8px\u00bb button_one_border_color=\u00bb#02d002&#8243; button_one_border_radius=\u00bb0px\u00bb button_one_letter_spacing=\u00bb1px\u00bb button_one_font=\u00bbLato|700|||||||\u00bb button_one_use_icon=\u00bboff\u00bb custom_button_two=\u00bbon\u00bb button_two_text_size=\u00bb18px\u00bb button_two_text_color=\u00bb#353740&#8243; button_two_bg_color=\u00bb#ffffff\u00bb button_two_border_width=\u00bb8px\u00bb button_two_border_color=\u00bb#ffffff\u00bb button_two_border_radius=\u00bb0px\u00bb button_two_letter_spacing=\u00bb1px\u00bb button_two_font=\u00bbLato|700|||||||\u00bb button_two_use_icon=\u00bboff\u00bb min_height=\u00bb640px\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb10%||10%|\u00bb button_one_letter_spacing_hover=\u00bb1px\u00bb button_two_letter_spacing_hover=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb1px\u00bb button_two_letter_spacing__hover_enabled=\u00bbon\u00bb button_two_letter_spacing__hover=\u00bb1px\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><span>Una semana de talleres para el autoempoderamiento<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbMarket Information Section\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb100px||100px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; admin_label=\u00bbMarket Information Title Area\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb40px|0px|40px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTitle\u00bb _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbLato||||||||\u00bb header_2_font_size=\u00bb36px\u00bb header_2_line_height=\u00bb1.5em\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbleft\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera, buena compa\u00f1\u00eda<\/h2>\n<h2><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb animation_direction=\u00bbleft\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>En plena naturaleza, en nuestro barranco valle, despertado por el canto de los p\u00e1jaros y los cencerros de las cabras, rodeado de escarpadas rocas y la tunera espinosa, donde las patatas y las verduras prosperan en los campos y donde suena de vez en cuando el silbo de un cabrero, all\u00ed puedes sumergirte por completo en la vida del campo canario. Puedes acompa\u00f1arnos y aprender con nosotros en nuestro d\u00eda a d\u00eda durante una semana. Puedes experimentarte a ti mismo en contacto con plantas y animales, sudar, crear algo duradero, apreciarte a ti mismo y al medio ambiente. Y encuentra tu fuerza de nuevo.<\/span><\/p>\n<p><span>La semana de empoderamiento incluye 30 horas de taller y 6 comidas caseras ecol\u00f3gicas. <\/span><\/p>\n<p><span>Las actividades incluyen: ruta bot\u00e1nica por el barranco, introducci\u00f3n a la jardiner\u00eda autosuficiente en armon\u00eda con la naturaleza, taller de mojo canario, introducci\u00f3n en terapia hort\u00edcola, construcci\u00f3n de muros de piedra seca, visita a varios proyectos de permacultura, cester\u00eda de la palmera canaria y reforestaci\u00f3n y plantaci\u00f3n de \u00e1rboles aut\u00f3ctonos.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbDirecci\u00f3n\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe01d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; image_icon_width=\u00bb67px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb27px\u00bb header_line_height=\u00bb1.6em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb18px\u00bb background_color=\u00bb#008f39&#8243; background_layout=\u00bbdark\u00bb custom_padding=\u00bb31px|20px|31px|20px|true|true\u00bb animation=\u00bboff\u00bb hover_enabled=\u00bb0&#8243; border_radii=\u00bbon|10px|10px|10px|10px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bb#727272&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><span>Hay diferentes posibilidades en la preciosa isla de La Gomera<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbTiempo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x7d;||divi||400&#8243; icon_color=\u00bb#4cbb17&#8243; image_icon_width=\u00bb67px\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb27px\u00bb header_line_height=\u00bb1.6em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb18px\u00bb custom_padding=\u00bb21px|10px|21px|10px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bb#727272&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Duraci\u00f3n: 30 H. en 7 d\u00edas<\/p>\n<p>Cu\u00e1ndo: Consultar<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCostes\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf153;||fa||900&#8243; icon_color=\u00bb#4cbb17&#8243; image_icon_width=\u00bb67px\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb27px\u00bb header_line_height=\u00bb1.6em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb18px\u00bb custom_padding=\u00bb19px|23px|19px|23px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bb#727272&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Pregunta por un presupuesto. Grupos peque\u00f1os: \u00a1m\u00e1ximo 8 personas!<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbLlegada\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe01d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; image_icon_width=\u00bb67px\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb27px\u00bb header_line_height=\u00bb1.6em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_font_size=\u00bb18px\u00bb background_color=\u00bb#008f39&#8243; background_layout=\u00bbdark\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bb#727272&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Independiente, se puede organizar el transporte para grupos m\u00e1s grandes<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion open_toggle_text_color=\u00bb#212121&#8243; closed_toggle_background_color=\u00bbrgba(76,187,23,0.7)\u00bb icon_color=\u00bb#008f39&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb toggle_text_color=\u00bb#FFFFFF\u00bb toggle_font=\u00bb|600|||||||\u00bb body_font_size=\u00bb17px\u00bb border_radii=\u00bbon|7px|7px|7px|7px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bb1\u00aa D\u00eda\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Llegada, paseo por La Laja (\u201cGassi village tour\u201d), cena juntos.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb2\u00ba D\u00eda\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><strong><span>Cultiva tu propia comida<\/span><\/strong><span>: introducci\u00f3n a la jardiner\u00eda autosuficiente en armon\u00eda con la naturaleza, recorrido por los campos, algo de trabajo, cosecha de ingredientes para el almuerzo. Taller de mojo, almuerzo juntos, teor\u00eda sobre t\u00e9\/caf\u00e9: terapia de jard\u00edn, conexi\u00f3n con la naturaleza y empoderamiento).<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb3\u00ba D\u00eda\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><strong><span>Realice un trabajo permanente usted mismo<\/span><\/strong><span>: construya un muro de piedra seca (introducci\u00f3n, preparaci\u00f3n del sitio, t\u00e9cnica de muro doble y simple con drenaje, colocaci\u00f3n de piedras, relleno con tierra), almuerzo en el sitio.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb4\u00ba D\u00eda\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><strong><span>Asumir la responsabilidad de uno mismo &#8211; Permacultura<\/span><\/strong><span>: conferencia y excursi\u00f3n, visita a varios proyectos de permacultura en la isla.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb5\u00ba D\u00eda\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><span>Libre &#8211; ba\u00f1o de bosque o senderismo si est\u00e1 interesado.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb6\u00ba D\u00eda\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><strong><span>Haz tu propio contenedor:<\/span><\/strong><span>\u00a0tejido de cestas con escobas de palma, almuerzo.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb7\u00ba D\u00eda\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><strong><span>Haz una declaraci\u00f3n<\/span><\/strong><span>: reforestaci\u00f3n con tus propias manos.\u00a0Cena de graduaci\u00f3n.<\/span><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb disabled_on=\u00bbon|on|on\u00bb disabled=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d225232.38276519367!2d-17.2144755!3d28.1082293!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xc6ae57bcd8ae58f%3A0x28dc34f3ee072b9d!2sGomera%20Rural%20Life%20Experience!5e0!3m2!1ses!2ses!4v1685614502166!5m2!1ses!2ses\" width=\"2600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; specialty=\u00bbon\u00bb padding_top_1=\u00bb0px\u00bb padding_bottom_1=\u00bb0px\u00bb admin_label=\u00bbImage Gallery Section\u00bb module_class=\u00bb et_pb_specialty_fullwidth\u00bb _builder_version=\u00bb4.21.0&#8243; inner_width=\u00bb100%\u00bb inner_width_tablet=\u00bb100%\u00bb inner_width_phone=\u00bb100%\u00bb inner_width_last_edited=\u00bbon|desktop\u00bb inner_max_width=\u00bb91%\u00bb inner_max_width_tablet=\u00bb100%\u00bb inner_max_width_phone=\u00bb100%\u00bb inner_max_width_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb make_fullwidth=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/fabi.production.jpg\u00bb alt=\u00bbvalle La Laja\u00bb title_text=\u00bbLa Laja 1&#8243; show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(0,0,0,0.3)\u00bb hover_icon=\u00bb&#x30;||divi||400&#8243; force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb|||\u00bb box_shadow_style=\u00bbpreset7&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb8px\u00bb box_shadow_color=\u00bb#ffffff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/P1100747.jpg\u00bb alt=\u00bbcetacea\u00bb title_text=\u00bbplanta cetacea\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(0,0,0,0.3)\u00bb hover_icon=\u00bb&#x30;||divi||400&#8243; force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb|||\u00bb box_shadow_style=\u00bbpreset7&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb8px\u00bb box_shadow_color=\u00bb#ffffff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/20201023_115240.jpg\u00bb alt=\u00bbcreando muro\u00bb title_text=\u00bbpared de piedra\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(0,0,0,0.3)\u00bb hover_icon=\u00bb&#x30;||divi||400&#8243; force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb|||\u00bb box_shadow_style=\u00bbpreset7&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb8px\u00bb box_shadow_color=\u00bb#ffffff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/P1160368.jpg\u00bb alt=\u00bbverduras 2&#8243; title_text=\u00bbcomposici\u00f3n verduras\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(0,0,0,0.3)\u00bb hover_icon=\u00bb&#x30;||divi||400&#8243; force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb|||\u00bb box_shadow_style=\u00bbpreset7&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb8px\u00bb box_shadow_color=\u00bb#ffffff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeature Section\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb56px||26px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbQuote Text Area\u00bb _builder_version=\u00bb4.21.0&#8243; custom_padding=\u00bb|0px|90px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text quote_border_weight=\u00bb10px\u00bb quote_border_color=\u00bb#7cda24&#8243; admin_label=\u00bbQuote\u00bb _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb13px\u00bb quote_font=\u00bbLato||on||||||\u00bb quote_text_color=\u00bb#333333&#8243; quote_font_size=\u00bb48px\u00bb quote_line_height=\u00bb1.5em\u00bb header_font=\u00bb||||||||\u00bb header_font_size=\u00bb24px\u00bb header_2_font_size=\u00bb19px\u00bb header_4_font=\u00bb||on||||||\u00bb header_4_font_size=\u00bb23px\u00bb header_4_line_height=\u00bb1.3em\u00bb header_6_font_size=\u00bb23px\u00bb header_6_line_height=\u00bb1.3em\u00bb max_width=\u00bb800px\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbleft\u00bb quote_font_size_tablet=\u00bb\u00bb quote_font_size_phone=\u00bb36px\u00bb quote_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<blockquote>\n<h4><span class=\"Y2IQFc\" lang=\"es\"><span>Puedo cambiar el mundo, con mis propias manos,<br \/>crear un lugar mejor, con mis propias manos,<br \/>crear un lugar m\u00e1s amable, con mis propias manos<\/span><\/span><\/h4>\n<h4><strong><span class=\"Y2IQFc\" lang=\"es\">Ben Harper<\/span><\/strong><\/h4>\n<\/blockquote>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; admin_label=\u00bbFeature 02 Area\u00bb _builder_version=\u00bb4.21.0&#8243; background_color=\u00bb#008f39&#8243; custom_margin=\u00bb||80px|\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb5%|5%|5%|5%\u00bb custom_padding_tablet=\u00bb0px|0px|0px|0px\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb0px|0px|0px|0px\u00bb padding_last_edited=\u00bboff|desktop\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTitle\u00bb _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbLato||||||||\u00bb header_2_font_size=\u00bb36px\u00bb header_2_line_height=\u00bb1.5em\u00bb background_layout=\u00bbdark\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||15px|\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbleft\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfQu\u00e9 es Gomera Rural Life Experience?<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb525px\u00bb module_alignment=\u00bbleft\u00bb animation_style=\u00bbflip\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_flip=\u00bb20%\u00bb animation_starting_opacity=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Es una oportunidad para experimentar la vida rural en La Gomera de forma aut\u00e9ntica y de primera mano. Gomera Rural Life Experience es activo &#8211; t\u00fa eres el que crea, hace y experimenta algo especial-. S\u00f3lo trabajo con grupos peque\u00f1os, siempre respondiendo individualmente a las necesidades de los participantes. Trabajamos con &#8211; y no contra la naturaleza-, con &#8211; y no contra las personas-. Damos importancia a comunicaci\u00f3n mindful y al uso consciente de los recursos.<\/span><span><\/span><\/p>\n<p><span>\u00a0<\/span><\/p>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bbUsamos productos nuestros y ecol\u00f3gicos de la isla\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x3d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_line_height=\u00bb1.1em\u00bb body_font=\u00bb|600|||||||\u00bb body_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbIntentamos no producir basura\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x3d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bb|600|||||||\u00bb body_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbApoyamos la agricultura ecol\u00f3gica y la Biodiversidad \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x3d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_line_height=\u00bb1.1em\u00bb body_font=\u00bb|600|||||||\u00bb body_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbValoramos la artesan\u00eda tradicional y el patrimonio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x3d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_line_height=\u00bb1.1em\u00bb body_font=\u00bb|600|||||||\u00bb body_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbCultivamos una actitud consciente y apreciativa\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x3d;||divi||400&#8243; icon_color=\u00bb#7cda24&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_line_height=\u00bb1.1em\u00bb body_font=\u00bb|600|||||||\u00bb body_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/IMG_20230528_173034.jpg\u00bb alt=\u00bbcesta de tomates\u00bb title_text=\u00bbcanasta de tomates\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb-40px||-40px|\u00bb custom_padding=\u00bb|40px||\u00bb animation_direction=\u00bbleft\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_blur=\u00bb80px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/P1160400.jpg\u00bb alt=\u00bbverduras\u00bb title_text=\u00bbVerdura foto 1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb281.3px\u00bb custom_margin=\u00bb85px|||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_module=\u00bb642&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb25px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/profile.php?id=100089764352967&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#3b5998&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/gomeracorazonverde\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ea2c59&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbtripadvisor\u00bb url=\u00bbhttps:\/\/www.tripadvisor.es\/Attraction_Review-g187469-d25268648-Reviews-Gomera_Rural_Life_Experience-La_Gomera_Canary_Islands.html\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#00af87&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]tripadvisor[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbgoogle\u00bb url=\u00bbhttps:\/\/www.google.com\/maps\/place\/Gomera+Rural+Life+Experience\/@28.1111475,-17.3292227,11z\/data=!4m15!1m8!3m7!1s0xc6ae57bcd8ae58f:0x28dc34f3ee072b9d!2sGomera+Rural+Life+Experience!8m2!3d28.1111475!4d-17.189147!10e5!16s%2Fg%2F11s9xnt_2b!3m5!1s0xc6ae57bcd8ae58f:0x28dc34f3ee072b9d!8m2!3d28.1111475!4d-17.189147!16s%2Fg%2F11s9xnt_2b?entry=ttu\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#4285f4&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]google[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb admin_label=\u00bbCall to Action\u00bb _builder_version=\u00bb4.21.0&#8243; animation_direction=\u00bbbottom\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbActividades en contacto con la Naturaleza\u00bb button_one_text=\u00bbActividades\u00bb button_one_url=\u00bbhttps:\/\/gomeracorazonverde.com\/actividades\/\u00bb button_two_text=\u00bbContacto\u00bb button_two_url=\u00bbhttps:\/\/gomeracorazonverde.com\/contacto\/\u00bb content_max_width=\u00bb800px\u00bb _builder_version=\u00bb4.21.0&#8243; title_level=\u00bbh2&#8243; title_font=\u00bbLato||||||||\u00bb title_font_size=\u00bb60px\u00bb title_line_height=\u00bb1.2em\u00bb content_font=\u00bb||||||||\u00bb content_font_size=\u00bb20px\u00bb content_line_height=\u00bb1.8em\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb90deg\u00bb background_color_gradient_stops=\u00bbrgba(0,0,0,0.75) 0%|rgba(0,0,0,0) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,0,0,0.75)\u00bb background_color_gradient_end=\u00bbrgba(0,0,0,0)\u00bb background_image=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/20200325_075423_RichtoneHDR.jpg\u00bb custom_button_one=\u00bbon\u00bb button_one_text_size=\u00bb18px\u00bb button_one_bg_color=\u00bb#02d002&#8243; button_one_border_width=\u00bb8px\u00bb button_one_border_color=\u00bb#02d002&#8243; button_one_border_radius=\u00bb0px\u00bb button_one_letter_spacing=\u00bb1px\u00bb button_one_font=\u00bbLato|700|||||||\u00bb button_one_use_icon=\u00bboff\u00bb custom_button_two=\u00bbon\u00bb button_two_text_size=\u00bb18px\u00bb button_two_text_color=\u00bb#353740&#8243; button_two_bg_color=\u00bb#ffffff\u00bb button_two_border_width=\u00bb8px\u00bb button_two_border_color=\u00bb#ffffff\u00bb button_two_border_radius=\u00bb0px\u00bb button_two_letter_spacing=\u00bb1px\u00bb button_two_font=\u00bbLato|700|||||||\u00bb button_two_use_icon=\u00bboff\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb8%||8%|\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb39px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb button_one_letter_spacing_hover=\u00bb1px\u00bb button_two_letter_spacing_hover=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb1px\u00bb button_two_letter_spacing__hover_enabled=\u00bbon\u00bb button_two_letter_spacing__hover=\u00bb1px\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb8px||11px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2399px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb background_color=\u00bb#000000&#8243; custom_margin=\u00bb-21px|||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">FINANCIADO POR LA UNI\u00d3N EUROPEA CON EL PROGRAMA KIT DIGITAL POR LOS FONDOS NEXT GENERATION (EU) DEL MECANISMO DE RECUPERACI\u00d3N Y RESILIENCIA<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb81%\u00bb max_width=\u00bb2450px\u00bb custom_margin=\u00bb-6px|auto||auto||\u00bb custom_padding=\u00bb11px||5px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/03\/logo-kd-financia-unioneuropea.jpg\u00bb alt=\u00bbFinanciado por la Uni\u00f3n Europea. Next Generation (EU)\u00bb title_text=\u00bbFinanciado por la Uni\u00f3n Europea. Next Generation (EU)\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/03\/logo-kd-gobierno-spain.jpg\u00bb alt=\u00bbGobierno de Espa\u00f1a\u00bb title_text=\u00bbGobierno de Espa\u00f1a\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/03\/logo-kd-prtr.jpg\u00bb alt=\u00bbPlan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia\u00bb title_text=\u00bbPlan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/03\/logo-kd-redes.jpg\u00bb alt=\u00bbred.es &#8211; Kit Digital\u00bb title_text=\u00bbred.es &#8211; Kit Digital\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Una semana de talleres para el autoempoderamiento &nbsp;Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera, buena compa\u00f1\u00eda En plena naturaleza, en nuestro barranco valle, despertado por el canto de los p\u00e1jaros y los cencerros de las cabras, rodeado de escarpadas rocas y la tunera espinosa, donde las patatas y las verduras prosperan en los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-292","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEMANA EMPODERAMIENTO - Gomera coraz\u00f3n verde<\/title>\n<meta name=\"description\" content=\"Una semana de talleres para el autoempoderamiento. Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera y buena compa\u00f1\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gomeracorazonverde.com\/de\/semana-empoderamiento\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEMANA EMPODERAMIENTO - Gomera coraz\u00f3n verde\" \/>\n<meta property=\"og:description\" content=\"Una semana de talleres para el autoempoderamiento. Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera y buena compa\u00f1\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gomeracorazonverde.com\/de\/semana-empoderamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Gomera coraz\u00f3n verde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089764352967\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T16:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/logomenu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"272\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/semana-empoderamiento\\\/\",\"url\":\"https:\\\/\\\/gomeracorazonverde.com\\\/semana-empoderamiento\\\/\",\"name\":\"SEMANA EMPODERAMIENTO - Gomera coraz\u00f3n verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/#website\"},\"datePublished\":\"2023-06-06T07:24:33+00:00\",\"dateModified\":\"2025-09-19T16:14:33+00:00\",\"description\":\"Una semana de talleres para el autoempoderamiento. Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera y buena compa\u00f1\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/semana-empoderamiento\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gomeracorazonverde.com\\\/semana-empoderamiento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/semana-empoderamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gomeracorazonverde.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEMANA EMPODERAMIENTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/#website\",\"url\":\"https:\\\/\\\/gomeracorazonverde.com\\\/\",\"name\":\"Gomera coraz\u00f3n verde\",\"description\":\"Talleres\",\"publisher\":{\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gomeracorazonverde.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/#organization\",\"name\":\"Gomera coraz\u00f3n verde\",\"url\":\"https:\\\/\\\/gomeracorazonverde.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gomeracorazonverde.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logomenu.jpg\",\"contentUrl\":\"https:\\\/\\\/gomeracorazonverde.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logomenu.jpg\",\"width\":272,\"height\":100,\"caption\":\"Gomera coraz\u00f3n verde\"},\"image\":{\"@id\":\"https:\\\/\\\/gomeracorazonverde.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089764352967\",\"https:\\\/\\\/www.instagram.com\\\/rural_life_gomera\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEMANA EMPODERAMIENTO - Gomera coraz\u00f3n verde","description":"Una semana de talleres para el autoempoderamiento. Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera y buena compa\u00f1\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gomeracorazonverde.com\/de\/semana-empoderamiento\/","og_locale":"de_DE","og_type":"article","og_title":"SEMANA EMPODERAMIENTO - Gomera coraz\u00f3n verde","og_description":"Una semana de talleres para el autoempoderamiento. Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera y buena compa\u00f1\u00eda.","og_url":"https:\/\/gomeracorazonverde.com\/de\/semana-empoderamiento\/","og_site_name":"Gomera coraz\u00f3n verde","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089764352967","article_modified_time":"2025-09-19T16:14:33+00:00","og_image":[{"width":272,"height":100,"url":"https:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/logomenu.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gomeracorazonverde.com\/semana-empoderamiento\/","url":"https:\/\/gomeracorazonverde.com\/semana-empoderamiento\/","name":"SEMANA EMPODERAMIENTO - Gomera coraz\u00f3n verde","isPartOf":{"@id":"https:\/\/gomeracorazonverde.com\/#website"},"datePublished":"2023-06-06T07:24:33+00:00","dateModified":"2025-09-19T16:14:33+00:00","description":"Una semana de talleres para el autoempoderamiento. Permacultura, cester\u00eda, muros de piedras, excursi\u00f3n, comida casera y buena compa\u00f1\u00eda.","breadcrumb":{"@id":"https:\/\/gomeracorazonverde.com\/semana-empoderamiento\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gomeracorazonverde.com\/semana-empoderamiento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gomeracorazonverde.com\/semana-empoderamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gomeracorazonverde.com\/"},{"@type":"ListItem","position":2,"name":"SEMANA EMPODERAMIENTO"}]},{"@type":"WebSite","@id":"https:\/\/gomeracorazonverde.com\/#website","url":"https:\/\/gomeracorazonverde.com\/","name":"Gomera coraz\u00f3n verde","description":"Talleres","publisher":{"@id":"https:\/\/gomeracorazonverde.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gomeracorazonverde.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gomeracorazonverde.com\/#organization","name":"Gomera coraz\u00f3n verde","url":"https:\/\/gomeracorazonverde.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gomeracorazonverde.com\/#\/schema\/logo\/image\/","url":"https:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/logomenu.jpg","contentUrl":"https:\/\/gomeracorazonverde.com\/wp-content\/uploads\/2023\/06\/logomenu.jpg","width":272,"height":100,"caption":"Gomera coraz\u00f3n verde"},"image":{"@id":"https:\/\/gomeracorazonverde.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089764352967","https:\/\/www.instagram.com\/rural_life_gomera\/"]}]}},"_links":{"self":[{"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/pages\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/comments?post=292"}],"version-history":[{"count":5,"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/pages\/292\/revisions"}],"predecessor-version":[{"id":734,"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/pages\/292\/revisions\/734"}],"wp:attachment":[{"href":"https:\/\/gomeracorazonverde.com\/de\/wp-json\/wp\/v2\/media?parent=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}